{"id":4896,"date":"2017-06-22T02:07:00","date_gmt":"2017-06-22T02:07:00","guid":{"rendered":"https:\/\/expedia.blog.de.sandwave.dev\/stories\/?p=4896"},"modified":"2021-09-01T22:12:52","modified_gmt":"2021-09-01T22:12:52","slug":"weihnachtsmarkte-schweiz","status":"publish","type":"post","link":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/","title":{"rendered":"Weihnachtsm\u00e4rkte Schweiz"},"content":{"rendered":"<p>&#8220;Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!<\/p>\n<p>Die zauberhafte Weihnachtswelt von Montreux und die malerische Sternenstadt St. Gallen sind nur einige der Highlights, die in einem Reisef\u00fchrer f\u00fcr Weihnachtsm\u00e4rkte in der Schweiz zu finden sind. Daneben stehen auch die Weihnachtsm\u00e4rkte in Bern und die Christkindlim\u00e4rkte in den Bahnh\u00f6fen Z\u00fcrich und Luzern f\u00fcr besinnliche Adventstraditionen. Romantische Weihnachtsm\u00e4rkte in der Schweiz gibt es aber auch am Lago Maggiore, an dessen Ufern die Kunsteisbahn von Locarno und die Weihnachtsbaumausstellung in Ascona zahlreiche Besucher anlocken.<\/p>\n<p>### Weihnachtsmarkt in Montreux &#8211; eine Zauberwelt f\u00fcr Familien<\/p>\n<p>Sehenswerte Attraktionen wie 160 Chalets an der Seepromenade und ein leuchtender Zaubergarten versetzen auf dem Weihnachtsmarkt von Montreux Besucher aller Altersgruppen in Staunen. In einem Reisef\u00fchrer f\u00fcr Weihnachtsm\u00e4rkte in der Schweiz ist die magische Welt Montreux Noel vertreten. Hier gibt es auf dem Rochers-de-Naye eine Grotte, in welcher Kinder den Weihnachtsmann treffen k\u00f6nnen. Auf der vorweihnachtlichen Entdeckungsreise im Dorf der Wichtel begegnen kleine Besucher hingegen Rentieren, Puppenspielern und Zirkusleuten. Im mittelalterlichen Schloss Chillon unterhalten Geschichtenerz\u00e4hler, Jongleure, T\u00e4nzer und Stelzenl\u00e4ufer das gro\u00dfe und kleine Publikum. Zur St\u00e4rkung gibt es mittelalterliche Speisen von einer Feuerstelle oder knusprige Holzofen-Pizzen aus dem Holzf\u00e4llerdorf.<\/p>\n<p>### Weihnachtsm\u00e4rkte in der Schweiz &#8211; festliches Altstadtflair in Bern und St. Gallen<\/p>\n<p>In der Liste der Reisetipps f\u00fcr Weihnachtsm\u00e4rkte in der Schweiz haben die Adventsm\u00e4rkte in Bern und St. Gallen einen besonderen Stellenwert. Der Berner Weihnachtsmarkt verwandelt beispielsweise den bekannten Waisenhausplatz in ein festliches Weihnachtsdorf mit Holzh\u00fctten und einem Zaun aus duftenden Tannenzweigen, der sich mit den Ger\u00fcchen von Tees und Gew\u00fcrzen vermischt. Au\u00dferdem f\u00fchrt die Suche nach handgefertigten Geschenken Stadtbesucher zum Kunsthandwerkermarkt am Berner M\u00fcnsterplatz, wo Unikate wie Keramikbecher, Seidenschals, Kerzen, Glasarbeiten und Drechslerwaren zum St\u00f6bern und Kaufen einladen. Romantiker schlendern im Glanz der AllerStern, einem magischen Lichtermeer mit 700 Sternen, \u00fcber den St. Galler Weihnachtsmarkt. Insider nehmen in St. Gallen an gef\u00fchrten Stadtrundg\u00e4ngen teil, um die Altstadtgassen der Schweizer Sternenstadt und den Stiftsbezirk bei Weihnachtsanekdoten kennenzulernen.<\/p>\n<p>### Christkindlim\u00e4rkte in den Bahnh\u00f6fen Z\u00fcrich und Luzern<\/p>\n<p>Wer seine Adventseink\u00e4ufe gerne in beheizten Hallen erledigen m\u00f6chte, kann als Reisetipps f\u00fcr Weihnachtsm\u00e4rkte in der Schweiz die Christkindlim\u00e4rkte in den Bahnh\u00f6fen von Z\u00fcrich und Luzern besuchen. Im Herzen des Z\u00fcrcher Christkindlimarktes entdecken Einkaufswillige, die nach Textilien, Handwerksst\u00fccken und Christstollen suchen, einen m\u00e4chtigen Tannenbaum mit einem funkelnden Lichtermeer aus Swarovski-Kristallen. Mit sch\u00f6nem Kunsthandwerk und kulinarischen Leckerbissen lockt auch der Christkindlimarkt in der Luzerner Bahnhofshalle, der f\u00fcr Musikinteressierte ein Konzertprogramm auf der Engelsstimmen-B\u00fchne bietet. Der Christkindli-M\u00e4rt in Bremgarten ist hingegen f\u00fcr seine wei\u00dfen Kutschen bekannt. Vom Spittelturm aus \u00fcberblicken Besucher das festlich beleuchtete Marktgel\u00e4nde dieser alten Stadt. In Bremgarten ist au\u00dferdem das Kerzenziehen beliebt, das auch auf dem B\u00fcrkliplatz in Z\u00fcrich zu den Weihnachtstraditionen geh\u00f6rt. Nur rund 45 Fahrminuten von Z\u00fcrich entfernt, bietet das Kloster Einsiedeln ein einzigartiges Ambiente f\u00fcr einen Weihnachtsmarkt, der auf dem Klosterplatz und in der Hauptstra\u00dfe zum vorweihnachtlichen Bummeln einl\u00e4dt.<\/p>\n<p>### Weihnachtsm\u00e4rkte in der Schweiz: malerischer Advent am Lago Maggiore und am Luganer See<\/p>\n<p>Die Schweizer Weihnachtsm\u00e4rkte am Lago Maggiore sind hingegen wegen ihrer stimmungsvollen Weihnachtsatmosph\u00e4re vor einer malerischen Seekulisse beliebt. In Locarno stimmen sich die Marktbesucher beispielsweise beim Schlittschuhlaufen auf der Piazza Grande und bei Live-Konzerten auf Weihnachten ein. Hier verw\u00f6hnen die Gastronomiebetriebe ihre G\u00e4ste in gro\u00dfen Iglu-Bars und kleinen Chalets mit kulinarischen K\u00f6stlichkeiten. Insider besuchen auch die Weihnachtsbaumausstellung auf dem Weihnachtsmarkt in der Nachbarortschaft Ascona. Neben Spazierg\u00e4ngen auf der Seepromenade geh\u00f6ren in Ascona auch das Weihnachtsrennen durch die Altstadt und das Neujahrskonzert zu den allj\u00e4hrlichen Attraktionen. Das romantische Weihnachtsdorf auf der Piazza Riforma in Lugano wird hingegen allj\u00e4hrlich mit der Entz\u00fcndung des Christbaumes feierlich er\u00f6ffnet.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!<\/p>\n","protected":false},"author":6,"featured_media":4897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[96],"tags":[35],"authors":[],"class_list":["post-4896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-christmas","tag-christmas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Weihnachtsm\u00e4rkte Schweiz<\/title>\n<meta name=\"description\" content=\"Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachtsm\u00e4rkte Schweiz\" \/>\n<meta property=\"og:description\" content=\"Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.de\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-22T02:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:12:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/24000\/24384-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/\",\"url\":\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/\",\"name\":\"Weihnachtsm\u00e4rkte Schweiz\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.de\/stories\/#website\"},\"datePublished\":\"2017-06-22T02:07:00+00:00\",\"dateModified\":\"2021-09-01T22:12:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.de\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.de\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weihnachten\",\"item\":\"https:\/\/www.expedia.de\/stories\/christmas\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weihnachtsm\u00e4rkte Schweiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.de\/stories\/#website\",\"url\":\"https:\/\/www.expedia.de\/stories\/\",\"name\":\"Expedia.de\",\"description\":\"Eure Reise beginnt hier!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.de\/stories\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.de\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.de\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.de\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachtsm\u00e4rkte Schweiz","description":"Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/","og_locale":"en_US","og_type":"article","og_title":"Weihnachtsm\u00e4rkte Schweiz","og_description":"Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!","og_url":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/","og_site_name":"Expedia.de","article_published_time":"2017-06-22T02:07:00+00:00","article_modified_time":"2021-09-01T22:12:52+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/24000\/24384-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/","url":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/","name":"Weihnachtsm\u00e4rkte Schweiz","isPartOf":{"@id":"https:\/\/www.expedia.de\/stories\/#website"},"datePublished":"2017-06-22T02:07:00+00:00","dateModified":"2021-09-01T22:12:52+00:00","author":{"@id":"https:\/\/www.expedia.de\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Weihnachtsm\u00e4rkte in der Schweiz besuchen und genie\u00dfen: Entdecken Sie mit Expedia Christkindlim\u00e4rkte und zauberhafte Winterwelten in verschiedenen St\u00e4dten!","breadcrumb":{"@id":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.de\/stories\/weihnachtsmarkte-schweiz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.de\/stories\/"},{"@type":"ListItem","position":2,"name":"Weihnachten","item":"https:\/\/www.expedia.de\/stories\/christmas\/"},{"@type":"ListItem","position":3,"name":"Weihnachtsm\u00e4rkte Schweiz"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.de\/stories\/#website","url":"https:\/\/www.expedia.de\/stories\/","name":"Expedia.de","description":"Eure Reise beginnt hier!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.de\/stories\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.de\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.de\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.de\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/posts\/4896"}],"collection":[{"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/comments?post=4896"}],"version-history":[{"count":1,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/posts\/4896\/revisions"}],"predecessor-version":[{"id":9714,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/posts\/4896\/revisions\/9714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/media\/4897"}],"wp:attachment":[{"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/media?parent=4896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/categories?post=4896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/tags?post=4896"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.de\/stories\/wp-json\/wp\/v2\/authors?post=4896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}